{"id":2397,"date":"2026-07-21T16:59:06","date_gmt":"2026-07-21T15:59:06","guid":{"rendered":"https:\/\/staging.kambi.com\/o-que-fazemos\/"},"modified":"2026-08-31T19:50:23","modified_gmt":"2026-08-31T18:50:23","slug":"o-que-fazemos","status":"publish","type":"page","link":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/","title":{"rendered":"O que fazemos"},"content":{"rendered":"\n<section class=\"text-block block-spacer cta-spacer-default bm__container with-container alinhar-centro -sem-fundo\">\n  <div class=\"text-block__content largura-texto-padr\u00e3o\">\n          <h2 class=\"text-block__heading bm__h3\">A tecnologia de ponta da Kambi permite que operadores impulsionem seu desempenho por meio de uma poderosa rede de dados, expertise em trading, intelig\u00eancia artificial e ampla experi\u00eancia em mercados regulamentados.<\/h2>\n          <\/div>\n  <\/section>\n\n\n<section class=\"logos-block block-spacer\">\n  <div class=\"bm__container\">\n\n          <h2 class=\"bm__h5 logos-block__header\">Junte-se a mais de 70 dos principais operadores do mundo<\/h2>\n    \n          <div class=\"logos-block__grid\">\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Ballys.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/BetPlay.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/HRDigital-1.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Livescore-Group.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Rush-Street.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/OLG.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n                  <div class=\"logos-block__item\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Svenska-Spel.svg\"\n              alt=\"\"\n              loading=\"lazy\">\n          <\/div>\n              <\/div>\n    \n  <\/div>\n<\/section>\n\n\n<section class=\"dual-section-block block-spacer\" id=\"ds-6a9775c3d04c75.68725300\">\n  <div class=\"bm__container\">\n\n    \n      <div class=\"dual-section dual-section--left\">\n\n                  <div class=\"dual-section__image\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Whatwedo-Power-of-the-network.png\"\n              alt=\"\"\n              loading=\"lazy\" \/>\n          <\/div>\n        \n        <div class=\"dual-section__content\">\n          <div class=\"dual-section-text\">\n                          <h2 class=\"title bm__h3\">Descubra o poder da nossa rede global<\/h2>\n            \n                          <div class=\"excerpt\"><p>Todo operador fortalece a rede global. Cada intera\u00e7\u00e3o dos jogadores a torna ainda mais poderosa. Com mais de 70 parceiros e bilh\u00f5es de apostas processadas anualmente, a rede da Kambi cria um ciclo cont\u00ednuo de intelig\u00eancia que impulsiona uma precifica\u00e7\u00e3o mais precisa, uma gest\u00e3o de risco mais eficiente e inova\u00e7\u00e3o cont\u00ednua em produtos.  <\/p>\n<p>&nbsp;<\/p>\n<p>Essa vantagem vai al\u00e9m da teoria. Ela \u00e9 comprovada diariamente por meio da excel\u00eancia em trading, da qualidade dos produtos e de parcerias duradouras. Seja para uma solu\u00e7\u00e3o turnkey completa ou para odds de alta precis\u00e3o que complementem sua oferta atual, a Kambi oferece a vantagem competitiva necess\u00e1ria para transformar ambi\u00e7\u00e3o em resultados consistentes e sustent\u00e1veis.  <\/p>\n<\/div>\n            \n                          <div class=\"ctas\">\n                                  <div class=\"-cta\">\n                    <a class=\"cta -outline -tertiary\" href=\"https:\/\/www.kambi.com\/what-we-do\/odds-feed\/power-of-the-network\/\" aria-label=\"Descobre mais\">\n                      <span>Descobre mais<\/span>\n                    <\/a>\n                  <\/div>\n                              <\/div>\n                      <\/div>\n        <\/div>\n\n      <\/div>\n\n    \n      <div class=\"dual-section dual-section--right\">\n\n                  <div class=\"dual-section__image\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Turnkey-Sportsbook-UI-2.png\"\n              alt=\"\"\n              loading=\"lazy\" \/>\n          <\/div>\n        \n        <div class=\"dual-section__content\">\n          <div class=\"dual-section-text\">\n                          <h2 class=\"title bm__h3\">Sportsbook Turnkey<\/h2>\n            \n                          <div class=\"excerpt\"><p>A principal solu\u00e7\u00e3o completa de sportsbook do mundo, desenvolvida para operadores que buscam crescimento sustent\u00e1vel, seguran\u00e7a regulat\u00f3ria e uma experi\u00eancia integrada entre os canais digitais e de varejo. Com a confian\u00e7a de mais de 60 parceiros, a Kambi oferece tecnologia de alta performance e experi\u00eancias que impulsionam resultados. <\/p>\n<\/div>\n            \n                          <div class=\"ctas\">\n                                  <div class=\"-cta\">\n                    <a class=\"cta -outline -tertiary\" href=\"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/sportsbook-turnkey\/\" aria-label=\"Descobre mais\">\n                      <span>Descobre mais<\/span>\n                    <\/a>\n                  <\/div>\n                              <\/div>\n                      <\/div>\n        <\/div>\n\n      <\/div>\n\n    \n      <div class=\"dual-section dual-section--left\">\n\n                  <div class=\"dual-section__image\">\n            <img decoding=\"async\"\n              src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/home-odds-feed-liquidity.png\"\n              alt=\"\"\n              loading=\"lazy\" \/>\n          <\/div>\n        \n        <div class=\"dual-section__content\">\n          <div class=\"dual-section-text\">\n                          <h2 class=\"title bm__h3\">Odds Feed+<\/h2>\n            \n                          <div class=\"excerpt\"><p>Odds pr\u00e9-jogo e ao vivo de alta precis\u00e3o por meio de uma \u00fanica integra\u00e7\u00e3o via API. Tenha acesso a uma precifica\u00e7\u00e3o de alta qualidade, incluindo Bet Builder e player props, impulsionada por um pool global de liquidez de \u20ac17 bilh\u00f5es e pela intelig\u00eancia da rede global da Kambi. <\/p>\n<\/div>\n            \n                          <div class=\"ctas\">\n                                  <div class=\"-cta\">\n                    <a class=\"cta -outline -tertiary\" href=\"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/odds-feed\/\" aria-label=\"Descobre mais\">\n                      <span>Descobre mais<\/span>\n                    <\/a>\n                  <\/div>\n                              <\/div>\n                      <\/div>\n        <\/div>\n\n      <\/div>\n\n    \n  <\/div>\n<\/section>\n\n\n\n\n\n\n<section class=\"form-block block-spacer contact_form\"\n  style=\"--form-bg:url(https:\/\/www.kambi.com\/wp-content\/plugins\/kambi-blocks\/blocks\/form\/assets\/newsletter-gradient.webp);\">\n  <div class=\"bm__container form-block__wrapper\">\n    <div class=\"form-block__form\">\n      \n<div class=\"contact-form\">\n\n  <div class=\"contact-form__content\">\n          <h2 class=\"bm__h2 contact-form__heading\">Pronto para <span class=\"has-text-gradient-tri\"><strong>experimentar a vantagem da Kambi?<\/strong><\/span><\/h2>\n    \n          <h3 class=\"bm__h6 contact-form__subheading\">Entre em contato com a equipe da Kambi usando o formul\u00e1rio abaixo.<\/h3>\n      <\/div>\n\n\n  <div class=\"contact-form__embed\">\n    <script>\n      (window.hsFormsOnReady ||= []).push(_ => {\n        hbspt.forms.create({\n          region: \"eu1\",\n          portalId: \"26165901\",\n          formId: \"f466f3b6-2b93-4ba0-a3af-386b07cf1cd9\",\n          css: \"\",\n          cssRequired: \"\"\n        });\n      });\n    <\/script>\n  <\/div>\n\n<\/div>    <\/div>\n  <\/div>\n<\/section>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2397","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que fazemos - Kambi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que fazemos - Kambi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/\" \/>\n<meta property=\"og:site_name\" content=\"Kambi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T18:50:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kambi.com\\\/pt-br\\\/o-que-fazemos\\\/\",\"url\":\"https:\\\/\\\/www.kambi.com\\\/pt-br\\\/o-que-fazemos\\\/\",\"name\":\"O que fazemos - Kambi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kambi.com\\\/#website\"},\"datePublished\":\"2026-07-21T15:59:06+00:00\",\"dateModified\":\"2026-08-31T18:50:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kambi.com\\\/pt-br\\\/o-que-fazemos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kambi.com\\\/pt-br\\\/o-que-fazemos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kambi.com\\\/pt-br\\\/o-que-fazemos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kambi.com\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que fazemos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kambi.com\\\/#website\",\"url\":\"https:\\\/\\\/www.kambi.com\\\/\",\"name\":\"Kambi\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kambi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que fazemos - Kambi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/","og_locale":"pt_BR","og_type":"article","og_title":"O que fazemos - Kambi","og_url":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/","og_site_name":"Kambi","article_modified_time":"2026-08-31T18:50:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/","url":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/","name":"O que fazemos - Kambi","isPartOf":{"@id":"https:\/\/www.kambi.com\/#website"},"datePublished":"2026-07-21T15:59:06+00:00","dateModified":"2026-08-31T18:50:23+00:00","breadcrumb":{"@id":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kambi.com\/pt-br\/o-que-fazemos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kambi.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"O que fazemos"}]},{"@type":"WebSite","@id":"https:\/\/www.kambi.com\/#website","url":"https:\/\/www.kambi.com\/","name":"Kambi","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kambi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/pages\/2397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/comments?post=2397"}],"version-history":[{"count":3,"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/pages\/2397\/revisions"}],"predecessor-version":[{"id":4435,"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/pages\/2397\/revisions\/4435"}],"wp:attachment":[{"href":"https:\/\/www.kambi.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}