{"id":3778,"date":"2026-07-21T16:56:49","date_gmt":"2026-07-21T15:56:49","guid":{"rendered":"https:\/\/staging.kambi.com\/about-kambi\/key-personnel\/"},"modified":"2026-09-01T12:10:58","modified_gmt":"2026-09-01T11:10:58","slug":"personas-importantes","status":"publish","type":"page","link":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/","title":{"rendered":"Personas importantes"},"content":{"rendered":"\n<section class=\"text-block block-spacer cta-spacer-default bm__container with-container alinhar-centro -sem-fundo\">\n  <div class=\"text-block__content text-width-wide\">\n          <h2 class=\"text-block__heading \">Conoce a los l\u00edderes experimentados que impulsan el \u00e9xito de Kambi. Nuestro Consejo y equipo ejecutivo aportan d\u00e9cadas de experiencia en apuestas deportivas, tecnolog\u00eda y negocios para liderar la red de apuestas deportivas m\u00e1s poderosa del mundo.  <\/h2>\n          <\/div>\n  <\/section>\n<section class=\"people-grid-block block-spacer\">\n  <div class=\"bm__container\">\n\n    \n          <nav class=\"people-filters\" aria-label=\"Filter by department\" data-people-filters>\n                          <button type=\"button\" class=\"people-chip is-active\" data-department=\"board\" aria-pressed=\"true\">\n            Board          <\/button>\n                  <button type=\"button\" class=\"people-chip\" data-department=\"management\" aria-pressed=\"false\">\n            Management          <\/button>\n                  <button type=\"button\" class=\"people-chip\" data-department=\"sales\" aria-pressed=\"false\">\n            Sales          <\/button>\n              <\/nav>\n    \n    <div class=\"person-grid\" data-people-grid>\n      \n        \n<article class=\"person-card js-person is-dept-board is-head-of-board\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Anders-Strom-2.jpg\"\n                alt=\"Anders Str\u00f6m\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Anders Str\u00f6m            <\/h3>\n\n            <p class=\"person-card__role\">Chair &amp; Member of the Nomination Committee<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person \">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Andy-Roocroft.jpg\"\n                alt=\"Andy Roocroft\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Andy Roocroft            <\/h3>\n\n            <p class=\"person-card__role\">Head of PR &amp; Communications<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-board\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Benjie-Cherniak.jpg\"\n                alt=\"Benjie Cherniak\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Benjie Cherniak            <\/h3>\n\n            <p class=\"person-card__role\">Chair of the Remuneration Committee<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/David-Bretnitz.jpg\"\n                alt=\"David Bretnitz\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    David Bretnitz            <\/h3>\n\n            <p class=\"person-card__role\">VP Sales, Americas<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/David-Carter.jpg\"\n                alt=\"David Carter\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    David Carter            <\/h3>\n\n            <p class=\"person-card__role\">Chief Legal Officer<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/David-Kenyon.jpg\"\n                alt=\"David Kenyon\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    David Kenyon            <\/h3>\n\n            <p class=\"person-card__role\">Chief Financial Officer<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Dylan-Mitchard.jpg\"\n                alt=\"Dylan Mitchard\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Dylan Mitchard            <\/h3>\n\n            <p class=\"person-card__role\">Senior Sales Director<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Erik-Logdberg.jpg\"\n                alt=\"Erik L\u00f6gdberg\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Erik L\u00f6gdberg            <\/h3>\n\n            <p class=\"person-card__role\">Chief Product Officer<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/James-Letchford.jpg\"\n                alt=\"James Letchford\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    James Letchford            <\/h3>\n\n            <p class=\"person-card__role\">Director Pre-Sales<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Kevin-Cunningham.jpg\"\n                alt=\"Kevin Cunningham\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Kevin Cunningham            <\/h3>\n\n            <p class=\"person-card__role\">Head of Commercial Pre-Sales<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Kris-Saw-1.jpg\"\n                alt=\"Kris Saw\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Kris Saw            <\/h3>\n\n            <p class=\"person-card__role\">Chief Technology Officer<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-board\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Kristian-Nylen-2.jpg\"\n                alt=\"Kristian Nyl\u00e9n\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Kristian Nyl\u00e9n            <\/h3>\n\n            <p class=\"person-card__role\">Chair of the Strategy Committee, Member of the Remuneration Committee and Member of the Nomination Committee<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-board\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Marlene-Forsell.jpg\"\n                alt=\"Marlene Forsell\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Marlene Forsell            <\/h3>\n\n            <p class=\"person-card__role\">Chair of the Audit Committee<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Mateo-Lenoble.jpg\"\n                alt=\"Mateo Lenoble\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Mateo Lenoble            <\/h3>\n\n            <p class=\"person-card__role\">Head of Sales, LatAm<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Michelle-Unsworth.jpg\"\n                alt=\"Michelle Unsworth\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Michelle Unsworth            <\/h3>\n\n            <p class=\"person-card__role\">Chief People Officer <\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-board\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Patrick-Clase.jpg\"\n                alt=\"Patrick Clase\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Patrick Clase            <\/h3>\n\n            <p class=\"person-card__role\">Member of the Audit Committee and Member of the Strategy Committee<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person \">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Peter-Ranere.jpg\"\n                alt=\"Peter Ranere\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Peter Ranere            <\/h3>\n\n            <p class=\"person-card__role\">PR &amp; Communications Manager<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-board\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Ronnie-Bodinger-1.jpg\"\n                alt=\"Ronnie Bodinger \"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Ronnie Bodinger             <\/h3>\n\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management is-dept-sales is-head-of-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Sarah-Robertson-3.jpg\"\n                alt=\"Sarah Robertson\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Sarah Robertson            <\/h3>\n\n            <p class=\"person-card__role\">Chief Commercial Officer<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Saverio-Ciruolo.jpg\"\n                alt=\"Saverio Ciruolo\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Saverio Ciruolo            <\/h3>\n\n            <p class=\"person-card__role\">Pre-Sales Support Analyst<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-sales\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Tom-Bullen.jpg\"\n                alt=\"Tom Bullen\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Tom Bullen            <\/h3>\n\n            <p class=\"person-card__role\">Sales Director<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person \">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Tom-Lewis.jpg\"\n                alt=\"Tom Lewis\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Tom Lewis            <\/h3>\n\n            <p class=\"person-card__role\">PR &amp; Communications Manager<\/p>\n    \n    \n    \n<\/article>\n\n      \n        \n<article class=\"person-card js-person is-dept-management is-head-of-management\">\n\n    <div class=\"person-card__media\">\n                    <img\n                src=\"https:\/\/www.kambi.com\/wp-content\/uploads\/2026\/08\/Werner-Becher.jpg\"\n                alt=\"Werner Becher\"\n                loading=\"lazy\"\n                decoding=\"async\">\n            <\/div>\n\n    <h3 class=\"person-card__name\">\n                    Werner Becher            <\/h3>\n\n            <p class=\"person-card__role\">Chief Executive Officer<\/p>\n    \n    \n    \n<\/article>\n\n          <\/div>\n\n  <\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3752,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3778","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Personas importantes - www.kambi.com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personas importantes - www.kambi.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/\" \/>\n<meta property=\"og:site_name\" content=\"www.kambi.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T11:10:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.kambi.com\\\/es\\\/sobre-kambi\\\/personas-importantes\\\/\",\"url\":\"https:\\\/\\\/www.kambi.com\\\/es\\\/sobre-kambi\\\/personas-importantes\\\/\",\"name\":\"Personas importantes - www.kambi.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.kambi.com\\\/#website\"},\"datePublished\":\"2026-07-21T15:56:49+00:00\",\"dateModified\":\"2026-09-01T11:10:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.kambi.com\\\/es\\\/sobre-kambi\\\/personas-importantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.kambi.com\\\/es\\\/sobre-kambi\\\/personas-importantes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.kambi.com\\\/es\\\/sobre-kambi\\\/personas-importantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.kambi.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre Kambi\",\"item\":\"https:\\\/\\\/www.kambi.com\\\/es\\\/sobre-kambi\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Personas importantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.kambi.com\\\/#website\",\"url\":\"https:\\\/\\\/www.kambi.com\\\/\",\"name\":\"www.kambi.com\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.kambi.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Personas importantes - www.kambi.com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/","og_locale":"es_ES","og_type":"article","og_title":"Personas importantes - www.kambi.com","og_url":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/","og_site_name":"www.kambi.com","article_modified_time":"2026-09-01T11:10:58+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/","url":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/","name":"Personas importantes - www.kambi.com","isPartOf":{"@id":"https:\/\/www.kambi.com\/#website"},"datePublished":"2026-07-21T15:56:49+00:00","dateModified":"2026-09-01T11:10:58+00:00","breadcrumb":{"@id":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kambi.com\/es\/sobre-kambi\/personas-importantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kambi.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sobre Kambi","item":"https:\/\/www.kambi.com\/es\/sobre-kambi\/"},{"@type":"ListItem","position":3,"name":"Personas importantes"}]},{"@type":"WebSite","@id":"https:\/\/www.kambi.com\/#website","url":"https:\/\/www.kambi.com\/","name":"www.kambi.com","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kambi.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/pages\/3778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/comments?post=3778"}],"version-history":[{"count":4,"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/pages\/3778\/revisions"}],"predecessor-version":[{"id":4194,"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/pages\/3778\/revisions\/4194"}],"up":[{"embeddable":true,"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/pages\/3752"}],"wp:attachment":[{"href":"https:\/\/www.kambi.com\/es\/wp-json\/wp\/v2\/media?parent=3778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}